{"id":69,"date":"2009-10-05T23:11:00","date_gmt":"2009-10-05T23:11:00","guid":{"rendered":"http:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/"},"modified":"2009-10-05T23:11:00","modified_gmt":"2009-10-05T23:11:00","slug":"leijuntaa","status":"publish","type":"post","link":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/","title":{"rendered":"leijuntaa"},"content":{"rendered":"<p>Keskiviikkona ykk\u00f6sen tee:lle saapuu t\u00e4m\u00e4n n\u00e4k\u00f6inen Heinonen, tyylikkyys ennen kaikkea \ud83d\ude00<\/p>\n<p><\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a href=\"http:\/\/2.bp.blogspot.com\/_he3CR_dl-aE\/SspSfFsB5eI\/AAAAAAAAAJI\/B4s2MJBJ-88\/s1600-h\/uusheinonen1.JPG\"><img border=\"0\" src=\"http:\/\/2.bp.blogspot.com\/_he3CR_dl-aE\/SspSfFsB5eI\/AAAAAAAAAJI\/B4s2MJBJ-88\/s320\/uusheinonen1.JPG\" \/><\/a><\/div>\n<p>;DDDDDDD<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keskiviikkona ykk\u00f6sen tee:lle saapuu t\u00e4m\u00e4n n\u00e4k\u00f6inen Heinonen, tyylikkyys ennen kaikkea \ud83d\ude00 ;DDDDDDD<\/p>\n","protected":false},"author":199,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[189],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"leijuntaa - Jessen Pro-Blogi\" \/>\n<meta property=\"og:description\" content=\"Keskiviikkona ykk\u00f6sen tee:lle saapuu t\u00e4m\u00e4n n\u00e4k\u00f6inen Heinonen, tyylikkyys ennen kaikkea \ud83d\ude00 ;DDDDDDD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/\" \/>\n<meta property=\"og:site_name\" content=\"Jessen Pro-Blogi\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-05T23:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/_he3CR_dl-aE\/SspSfFsB5eI\/AAAAAAAAAJI\/B4s2MJBJ-88\/s320\/uusheinonen1.JPG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/#website\",\"url\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/\",\"name\":\"Jessen Pro-Blogi\",\"description\":\"Jesse Heinonen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fi\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/#primaryimage\",\"inLanguage\":\"fi\",\"url\":\"http:\/\/2.bp.blogspot.com\/_he3CR_dl-aE\/SspSfFsB5eI\/AAAAAAAAAJI\/B4s2MJBJ-88\/s320\/uusheinonen1.JPG\",\"contentUrl\":\"http:\/\/2.bp.blogspot.com\/_he3CR_dl-aE\/SspSfFsB5eI\/AAAAAAAAAJI\/B4s2MJBJ-88\/s320\/uusheinonen1.JPG\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/#webpage\",\"url\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/\",\"name\":\"leijuntaa - Jessen Pro-Blogi\",\"isPartOf\":{\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/#primaryimage\"},\"datePublished\":\"2009-10-05T23:11:00+00:00\",\"dateModified\":\"2009-10-05T23:11:00+00:00\",\"author\":{\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/#\/schema\/person\/37cd155c04e4e21258ff575d1001056b\"},\"breadcrumb\":{\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/\",\"url\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/\",\"url\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/2009\/10\/05\/leijuntaa\/\",\"name\":\"leijuntaa\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/#\/schema\/person\/37cd155c04e4e21258ff575d1001056b\",\"name\":\"jesse\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/#personlogo\",\"inLanguage\":\"fi\",\"url\":\"\/\/www.gravatar.com\/avatar\/992db49f106498ce8a9408a18cfae17d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\/\/www.gravatar.com\/avatar\/992db49f106498ce8a9408a18cfae17d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"jesse\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/posts\/69"}],"collection":[{"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/users\/199"}],"replies":[{"embeddable":true,"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":0,"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/posts\/69\/revisions"}],"wp:attachment":[{"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/media?parent=69"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/categories?post=69"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frisbeegolfradat.fi\/jesse_heinonen\/wp-json\/wp\/v2\/tags?post=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}